{"id":8575,"date":"2025-09-09T12:22:00","date_gmt":"2025-09-09T10:22:00","guid":{"rendered":"https:\/\/aeservice.fr\/electrolytic-capacitors\/"},"modified":"2025-10-15T16:08:53","modified_gmt":"2025-10-15T14:08:53","slug":"electrolytic-capacitors","status":"publish","type":"page","link":"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/","title":{"rendered":"Electrolytic Capacitors"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-left:0px;--awb-margin-top:0px;--awb-margin-bottom:-20px;--awb-background-color:var(--awb-color1);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:40px;--awb-padding-right:40px;--awb-padding-bottom:20px;--awb-padding-left:40px;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:var(--awb-color4);--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:40;line-height:1.25;\">Electrolytic Capacitors<\/h1><\/div><div class=\"fusion-text fusion-text-1\" style=\"--awb-content-alignment:justify;--awb-text-color:var(--awb-color4);\"><p><strong>Our electrolytic capacitors<\/strong> offer reliability, long lifespan, and low equivalent series resistance (ESR), for stable performance in industrial, railway, and electronic environments. Available in high-performance or standard versions, they can be <strong>customized<\/strong> according to your specific needs.<\/p>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_2_5 2_5 fusion-flex-column\" style=\"--awb-padding-right:10px;--awb-padding-left:10px;--awb-bg-size:cover;--awb-width-large:40%;--awb-margin-top-large:25px;--awb-spacing-right-large:4.8%;--awb-margin-bottom-large:25px;--awb-spacing-left-large:4.8%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:left;\"><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-span-no fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color5);--button_border_color:var(--awb-color5);--button_accent_hover_color:#eef0f3;--button_border_hover_color:#eef0f3;--button_gradient_top_color:var(--awb-color4);--button_gradient_bottom_color:var(--awb-color4);--button_gradient_top_color_hover:#003a7d;--button_gradient_bottom_color_hover:#003a7d;--button_typography-font-family:&quot;Space Grotesk&quot;;--button_typography-font-style:normal;--button_typography-font-weight:700;\" target=\"_self\" href=\"https:\/\/aeservice.fr\/contact-2\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Request a quote<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_3_5 3_5 fusion-flex-column\" style=\"--awb-padding-right:10px;--awb-padding-left:10px;--awb-bg-size:cover;--awb-width-large:60%;--awb-margin-top-large:25px;--awb-spacing-right-large:3.2%;--awb-margin-bottom-large:25px;--awb-spacing-left-large:3.2%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-2 fusion-button-span-no fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color5);--button_border_color:var(--awb-color5);--button_accent_hover_color:#eef0f3;--button_border_hover_color:#eef0f3;--button_gradient_top_color:var(--awb-color4);--button_gradient_bottom_color:var(--awb-color4);--button_gradient_top_color_hover:#003a7d;--button_gradient_bottom_color_hover:#003a7d;--button_typography-font-family:&quot;Space Grotesk&quot;;--button_typography-font-style:normal;--button_typography-font-weight:700;\" target=\"_self\" href=\"mailto:aeservice@aeservice.fr\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Learn more about this product<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:20px;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-1\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-below\" data-layout=\"carousel\" data-autoplay=\"yes\" data-autoplayspeed=\"2500\" data-autoplaypause=\"yes\" data-loop=\"yes\" data-columns=\"1.0\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:1.0;--awb-dots-color:#eef0f3;--awb-dots-active-color:#003a7d;--awb-dots-size:14px;--awb-dots-active-size:14px;--awb-dots-spacing:8px;--awb-dots-margin-top:30px;--awb-dots-align:center;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-kendeil.webp\" class=\"attachment-full size-full lazyload\" alt=\"condensateurs \u00e9lectrolytiques aluminium kendeil\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-kendeil.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-kendeil-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-kendeil-300x200.webp 300w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-kendeil-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-kendeil-500x333.webp 500w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-kendeil.webp 600w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium.webp\" class=\"attachment-full size-full lazyload\" alt=\"condensateurs \u00e9lectrolytiques aluminium\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-300x200.webp 300w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium-500x333.webp 500w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-aluminium.webp 600w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-bornes-a-vis.webp\" class=\"attachment-full size-full lazyload\" alt=\"condensateurs \u00e9lectrolytiques bornes \u00e0 vis\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-bornes-a-vis.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-bornes-a-vis-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-bornes-a-vis-300x200.webp 300w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-bornes-a-vis-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-bornes-a-vis-500x333.webp 500w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-bornes-a-vis.webp 600w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-jb-capacitors.webp\" class=\"attachment-full size-full lazyload\" alt=\"condensateurs \u00e9lectrolytiques jb capacitors\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-jb-capacitors.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-jb-capacitors-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-jb-capacitors-300x200.webp 300w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-jb-capacitors-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-jb-capacitors-500x333.webp 500w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-jb-capacitors.webp 600w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-snap-in.webp\" class=\"attachment-full size-full lazyload\" alt=\"condensateurs \u00e9lectrolytiques snap-in\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-snap-in.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-snap-in-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-snap-in-300x200.webp 300w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-snap-in-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-snap-in-500x333.webp 500w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/condensateurs-electrolytiques-snap-in.webp 600w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><\/div><div class=\"swiper-pagination\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-left:0px;--awb-background-color:var(--awb-color1);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 awb-sticky awb-sticky-small awb-sticky-medium awb-sticky-large fusion_builder_column_1_5 1_5 fusion-flex-column fusion-flex-align-self-flex-start\" style=\"--awb-padding-top:60px;--awb-padding-right:20px;--awb-padding-bottom:180px;--awb-padding-left:10px;--awb-bg-color:var(--awb-color4);--awb-bg-color-hover:var(--awb-color4);--awb-bg-size:cover;--awb-width-large:20%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-bottom:80px;--awb-max-width:80px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"300\" title=\"Copy-of-[AE]-Emblem-Favicon\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-AE-Embleme-Favicon.png\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-AE-Embleme-Favicon-300x300.png\" alt class=\"lazyload img-responsive wp-image-7596\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27796%27%20height%3D%27796%27%20viewBox%3D%270%200%20796%20796%27%3E%3Crect%20width%3D%27796%27%20height%3D%27796%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-AE-Embleme-Favicon-200x200.png 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-AE-Embleme-Favicon-400x400.png 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-AE-Embleme-Favicon-600x600.png 600w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-AE-Embleme-Favicon.png 796w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-1 content-boxes-icon-on-side content-left\" style=\"--awb-title-color:var(--awb-color8);--awb-hover-accent-color:#2359a6;--awb-circle-hover-accent-color:#2359a6;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:75px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-slide\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-39-39.svg\" width=\"55\" height=\"55\" alt=\"\" \/><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:16px;--fontSize:16;line-height:1.3;padding-left:75px;\">Custom-made Solutions for your Electronic Projects<\/h3><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-2 content-boxes-icon-on-side content-left\" style=\"--awb-title-color:var(--awb-color8);--awb-hover-accent-color:#2359a6;--awb-circle-hover-accent-color:#2359a6;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:75px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-slide\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-38-38.svg\" width=\"55\" height=\"55\" alt=\"\" \/><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:16px;--fontSize:16;line-height:1.3;padding-left:75px;\">5,000m\u00b2 of Storage in France and Spain<\/h3><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-3 content-boxes-icon-on-side content-left\" style=\"--awb-title-color:var(--awb-color8);--awb-hover-accent-color:#2359a6;--awb-circle-hover-accent-color:#2359a6;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:75px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-slide\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-41-41.svg\" width=\"55\" height=\"55\" alt=\"\" \/><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:16px;--fontSize:16;line-height:1.3;padding-left:75px;\">Over 30 Years of Expertise Serving the Industry<\/h3><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-4 content-boxes-icon-on-side content-left\" style=\"--awb-title-color:var(--awb-color8);--awb-hover-accent-color:#2359a6;--awb-circle-hover-accent-color:#2359a6;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:75px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-slide\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-37-37.svg\" width=\"55\" height=\"55\" alt=\"\" \/><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:16px;--fontSize:16;line-height:1.3;padding-left:75px;\">A Team Based in Europe (France and Spain)<\/h3><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-5 content-boxes-icon-on-side content-left\" style=\"--awb-title-color:var(--awb-color8);--awb-hover-accent-color:#2359a6;--awb-circle-hover-accent-color:#2359a6;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:75px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-slide\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-43-43.svg\" width=\"55\" height=\"55\" alt=\"\" \/><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:16px;--fontSize:16;line-height:1.3;padding-left:75px;\">A Turnkey Service: Sourcing, Consulting, Logistics...<\/h3><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-1 fusion-content-boxes-6 content-boxes-icon-on-side content-left\" style=\"--awb-title-color:var(--awb-color8);--awb-hover-accent-color:#2359a6;--awb-circle-hover-accent-color:#2359a6;--awb-item-margin-bottom:40px;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:75px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-slide\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/Copie-de-39-39.svg\" width=\"55\" height=\"55\" alt=\"\" \/><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:16px;--fontSize:16;line-height:1.3;padding-left:75px;\">In-house R&amp;D for Optimized Technical Solutions<\/h3><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_4_5 4_5 fusion-flex-column\" style=\"--awb-padding-top:40px;--awb-padding-right:40px;--awb-padding-left:40px;--awb-bg-color:var(--awb-color1);--awb-bg-color-hover:var(--awb-color1);--awb-bg-size:cover;--awb-width-large:80%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color5);--awb-margin-top:-30px;--awb-margin-bottom:-20px;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:36px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:36;line-height:1.25;\"><h2>What is an Electrolytic Capacitor?<\/h2><\/h2><\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-content-alignment:justify;--awb-text-color:var(--awb-color6);\"><p><strong>An electrolytic capacitor<\/strong> is a passive component that stores electrical energy to release it into a circuit as needed. Their high capacitance and low ESR make them ideal for applications requiring stability, endurance, and energy efficiency. <\/p>\n<p>To meet various applications, we offer <strong>several types of capacitors<\/strong>.<\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-3 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-bottom:60px;--button_accent_color:#eef0f3;--button_accent_hover_color:#eef0f3;--button_border_hover_color:#eef0f3;--button_gradient_top_color:var(--awb-color6);--button_gradient_bottom_color:var(--awb-color6);--button_gradient_top_color_hover:#003a7d;--button_gradient_bottom_color_hover:#003a7d;\" target=\"_self\" href=\"https:\/\/aeservice.fr\/condensateurs\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Discover all our capacitor types<\/span><\/a><\/div><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color5);--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:36px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:36;line-height:1.25;\">Our range of electrolytic capacitors<\/h2><\/div><div class=\"fusion-text fusion-text-3\" style=\"--awb-content-alignment:justify;--awb-text-color:var(--awb-color6);\"><p>We distribute aluminum electrolytic capacitors <a href=\"https:\/\/aeservice.fr\/kendeil\/\"><br \/>\n  <strong>Kendeil<\/strong><br \/>\n<\/a>, manufactured in Italy, as well as our brand <a href=\"https:\/\/aeservice.fr\/slce\/\"><br \/>\n  <strong>SLCE<\/strong><br \/>\n<\/a>, offering reliable and high-performance solutions:<\/p>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-center\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:25px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:25px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><ul style=\"--awb-textcolor:#003a7d;--awb-line-height:30.6px;--awb-icon-width:30.6px;--awb-icon-height:30.6px;--awb-icon-margin:12.6px;--awb-content-margin:43.2px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-circle fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><strong>Screw terminals<\/strong>: 15000H, 85\u00b0C<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-circle fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><strong>Snap-in<\/strong>: 5000H, 105\u00b0C<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-circle fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Capacitors manufactured according to railway market standards<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-circle fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><strong>Custom<\/strong> options for your specific projects<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-circle fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Stock deliverable within 24\/48h with over 80,000 references available in our warehouse in France<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-circle fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><strong>Manufacturing lead times<\/strong>: 2 to 4 weeks<\/p>\n<\/div><\/li><\/ul><\/div><\/div><\/div><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color5);--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:36px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:36;line-height:1.25;\">Application areas<\/h2><\/div><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-2\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"no\" data-autoplayspeed=\"2500\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"3.0\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"1\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:3.0;--awb-caption-title-color:#003a7d;--awb-caption-title-size:25px;--awb-caption-text-color:#000000;--awb-caption-border-color:var(--awb-color6);--awb-caption-overlay-color:var(--awb-color4);--awb-border-radius-top-left:10px;--awb-border-radius-top-right:10px;--awb-border-radius-bottom-right:10px;--awb-border-radius-bottom-left:10px;--awb-arrow-size:50px;--awb-arrow-box-width:50px;--awb-arrow-box-height:50px;--awb-dots-align:center;--awb-caption-title-font-family:&quot;Space Grotesk&quot;;--awb-caption-title-font-style:normal;--awb-caption-title-font-weight:700;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper awb-imageframe-style awb-imageframe-style-resa\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/audio.webp\" class=\"attachment-full size-full lazyload\" alt=\"Audio\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/audio.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/audio-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/audio-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/audio.webp 600w\" data-sizes=\"auto\" \/><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h3 class=\"awb-imageframe-caption-title\">Audio<\/h3><p class=\"awb-imageframe-caption-text\">audio power supply quality<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper awb-imageframe-style awb-imageframe-style-resa\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/telecommunication.webp\" class=\"attachment-full size-full lazyload\" alt=\"Telecommunications\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/telecommunication.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/telecommunication-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/telecommunication-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/telecommunication.webp 600w\" data-sizes=\"auto\" \/><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h3 class=\"awb-imageframe-caption-title\">Telecommunications<\/h3><p class=\"awb-imageframe-caption-text\">high-frequency circuits<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper awb-imageframe-style awb-imageframe-style-resa\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/industrie.webp\" class=\"attachment-full size-full lazyload\" alt=\"Industry\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/industrie.webp\" data-srcset=\"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/industrie-200x133.webp 200w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/industrie-400x267.webp 400w, https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/09\/industrie.webp 600w\" data-sizes=\"auto\" \/><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h3 class=\"awb-imageframe-caption-title\">Industry<\/h3><p class=\"awb-imageframe-caption-text\">control and automation<\/p><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":44,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-8575","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Electrolytic Capacitors | European Manufacturing<\/title>\n<meta name=\"description\" content=\"Aluminum electrolytic capacitors manufactured in Italy. Railway certified and suitable for many sectors (energy, audio, medical...)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Electrolytic Capacitors | European Manufacturing\" \/>\n<meta property=\"og:description\" content=\"Aluminum electrolytic capacitors manufactured in Italy. Railway certified and suitable for many sectors (energy, audio, medical...)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/\" \/>\n<meta property=\"og:site_name\" content=\"AE Service Group\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T14:08:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"33 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/electrolytic-capacitors\\\/\",\"url\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/electrolytic-capacitors\\\/\",\"name\":\"Electrolytic Capacitors | European Manufacturing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/#website\"},\"datePublished\":\"2025-09-09T10:22:00+00:00\",\"dateModified\":\"2025-10-15T14:08:53+00:00\",\"description\":\"Aluminum electrolytic capacitors manufactured in Italy. Railway certified and suitable for many sectors (energy, audio, medical...)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/electrolytic-capacitors\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aeservice.fr\\\/en\\\/electrolytic-capacitors\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/electrolytic-capacitors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Electrolytic Capacitors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/\",\"name\":\"AE SERVICE GROUP\",\"description\":\"Penser global, agir sur-mesure\",\"publisher\":{\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/#organization\",\"name\":\"AE SERVICE GROUP\",\"url\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aeservice.fr\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AE-Logotype-Principal-Couleur.svg\",\"contentUrl\":\"https:\\\/\\\/aeservice.fr\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AE-Logotype-Principal-Couleur.svg\",\"width\":797,\"height\":309,\"caption\":\"AE SERVICE GROUP\"},\"image\":{\"@id\":\"https:\\\/\\\/aeservice.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/a-e-service\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Electrolytic Capacitors | European Manufacturing","description":"Aluminum electrolytic capacitors manufactured in Italy. Railway certified and suitable for many sectors (energy, audio, medical...)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/","og_locale":"en_US","og_type":"article","og_title":"Electrolytic Capacitors | European Manufacturing","og_description":"Aluminum electrolytic capacitors manufactured in Italy. Railway certified and suitable for many sectors (energy, audio, medical...)","og_url":"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/","og_site_name":"AE Service Group","article_modified_time":"2025-10-15T14:08:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"33 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/","url":"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/","name":"Electrolytic Capacitors | European Manufacturing","isPartOf":{"@id":"https:\/\/aeservice.fr\/en\/#website"},"datePublished":"2025-09-09T10:22:00+00:00","dateModified":"2025-10-15T14:08:53+00:00","description":"Aluminum electrolytic capacitors manufactured in Italy. Railway certified and suitable for many sectors (energy, audio, medical...)","breadcrumb":{"@id":"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aeservice.fr\/en\/electrolytic-capacitors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aeservice.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Electrolytic Capacitors"}]},{"@type":"WebSite","@id":"https:\/\/aeservice.fr\/en\/#website","url":"https:\/\/aeservice.fr\/en\/","name":"AE SERVICE GROUP","description":"Penser global, agir sur-mesure","publisher":{"@id":"https:\/\/aeservice.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aeservice.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aeservice.fr\/en\/#organization","name":"AE SERVICE GROUP","url":"https:\/\/aeservice.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aeservice.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/AE-Logotype-Principal-Couleur.svg","contentUrl":"https:\/\/aeservice.fr\/wp-content\/uploads\/2025\/08\/AE-Logotype-Principal-Couleur.svg","width":797,"height":309,"caption":"AE SERVICE GROUP"},"image":{"@id":"https:\/\/aeservice.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr.linkedin.com\/company\/a-e-service"]}]}},"_links":{"self":[{"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/pages\/8575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/comments?post=8575"}],"version-history":[{"count":6,"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/pages\/8575\/revisions"}],"predecessor-version":[{"id":8592,"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/pages\/8575\/revisions\/8592"}],"wp:attachment":[{"href":"https:\/\/aeservice.fr\/en\/wp-json\/wp\/v2\/media?parent=8575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}